{"id":56335,"date":"2024-01-17T15:11:34","date_gmt":"2024-01-17T18:11:34","guid":{"rendered":"https:\/\/quindim.com.br\/blog\/?p=56335"},"modified":"2025-05-21T05:51:56","modified_gmt":"2025-05-21T08:51:56","slug":"como-despertar-a-escrita-criativa","status":"publish","type":"post","link":"https:\/\/quindim.com.br\/blog\/como-despertar-a-escrita-criativa\/","title":{"rendered":"Como despertar a escrita criativa nas crian\u00e7as"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Percorrido o processo de alfabetiza\u00e7\u00e3o e letramento, com todas as dores e as del\u00edcias que dele fazem parte, acontece um fen\u00f4meno curioso: a estrada se bifurca e, para um lado, v\u00e3o aqueles que &#8220;sabem escrever&#8221;, enquanto para outro, numa via toda escura e chuvosa, se encaminham cabisbaixos os que &#8220;n\u00e3o sabem escrever&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesta vis\u00e3o comum do que se segue, <strong>o &#8220;saber&#8221; n\u00e3o teria rela\u00e7\u00e3o com o dom\u00ednio do sistema e do c\u00f3digo da escrita, mas sim com a aura quase m\u00e1gica que acompanha aqueles que n\u00e3o se apavoram diante de uma folha em branco<\/strong>. Como se, em resumo, saber escrever fosse algo reservado apenas aos que se sentem \u00e0 vontade com o processo criativo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"570\" height=\"410\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/12\/Como-despertar-a-escrita-criativa-nas-criancas-meio1.jpg\" alt=\"\" class=\"wp-image-56346\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/12\/Como-despertar-a-escrita-criativa-nas-criancas-meio1.jpg 570w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/12\/Como-despertar-a-escrita-criativa-nas-criancas-meio1-150x108.jpg 150w\" sizes=\"(max-width: 570px) 100vw, 570px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Pois eis a grande revela\u00e7\u00e3o: <strong>escrever \u00e9 pr\u00e1tica desconfort\u00e1vel para todos aqueles que nela se aventuram<\/strong>. Uns mais, outros menos, todos os escritores e as escritoras precisam sair do lugar quentinho e autom\u00e1tico do dia a dia para poder criar seus textos, mundos, relatos, fic\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O pensamento de que apenas alguns escolhidos teriam <strong>&#8220;o dom&#8221; de escrever \u00e9 partilhado pela grande maioria dos que amam a literatura e se interessam por criar suas pr\u00f3prias hist\u00f3rias, mas que se reprimem porque acreditam que este n\u00e3o \u00e9 um mundo para qualquer um.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pois ele \u00e9 para todos, e nem tem idade m\u00ednima para quem quer entrar. Generosa, a escrita criativa n\u00e3o exige dos interessados nada al\u00e9m do desejo de brincar. Brincar de agora eu era her\u00f3i e nossos cavalos s\u00f3 falavam ingl\u00eas, brincar de fazer os outros rirem, de emocion\u00e1-los, de cal\u00e7ar os sapatos de algu\u00e9m que eu conhe\u00e7o e ver como seria dan\u00e7ar com eles por alguns instantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Todo mundo sabe escrever<\/strong>. A diferen\u00e7a est\u00e1 na abertura que cada um tem para tudo que o processo exige: concentra\u00e7\u00e3o, perseveran\u00e7a, paci\u00eancia e tantas outras coisas sempre raras, mas ainda mais em tempos de dispers\u00e3o total diante das telas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As f\u00e9rias escolares s\u00e3o um excelente momento para adquirir junto da crian\u00e7a o h\u00e1bito da escrita por prazer (prazer com ligeiro desconforto, nunca esquecer!). <strong>Criar um di\u00e1rio de f\u00e9rias, com registros ou at\u00e9 mesmo na forma de um caderno ficcional, pode ser um excelente come\u00e7o<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, vale pensar que a escrita criativa tamb\u00e9m precisa de rotina para brotar, com regas sen\u00e3o di\u00e1rias semanais, no constante exerc\u00edcio de criar amor pelo que se faz. Ent\u00e3o, todo dia \u00e9 dia de escrever.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading subtituloh2\">5 <strong>Exerc\u00edcios divertidos de escrita criativa para trabalhar em sala de aula ou em casa<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Os temas abaixo convidam \u00e0 cria\u00e7\u00e3o em forma de texto, mas isso <strong>n\u00e3o significa que o momento de escrever precise ser engessado e mon\u00f3tono<\/strong>. Papel e caneta ou l\u00e1pis podem ser grandes amigos, mas n\u00e3o os \u00fanicos: caso o respons\u00e1vel ou educador perceba que estar diante da folha em branco \u00e9 angustiante para a crian\u00e7a, adicione elementos como recorte de figuras, colheita de elementos da natureza, grava\u00e7\u00e3o de \u00e1udios no celular etc. O texto pode, ent\u00e3o, vir a partir deles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais importante que o formato final, a escrita criativa busca conduzir o processo de inven\u00e7\u00e3o e emancipa\u00e7\u00e3o do pensamento. <strong>Permita que o jovem escritor reconhe\u00e7a e acolha seu pr\u00f3prio m\u00e9todo de criar.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veja tamb\u00e9m: <a href=\"https:\/\/quindim.com.br\/blog\/como-estimular-a-criatividade-infantil\/\" target=\"_blank\" rel=\"noreferrer noopener\">Como estimular a criatividade infantil? Descubra e aplique agora.<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/quindim.com.br\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"810\" height=\"189\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/04\/O-melhor-clube-de-assinatura-infantil.gif\" alt=\"O melhor clube de assinatura infantil\" class=\"wp-image-38466\" title=\"\"><\/a><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading subtituloh2\">1. <strong>ASTRONAUTA<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Crian\u00e7a, voc\u00ea \u00e9 a primeira ou o primeiro astronauta a pisar definitivamente em Marte. Sua miss\u00e3o \u00e9 a pioneira, e voc\u00ea foi enviada ou enviado para habitar o planeta vermelho. Voc\u00ea \u00e9 chefe de todos que estar\u00e3o l\u00e1. Ali\u00e1s, voc\u00ea sabe dizer se h\u00e1 mais algu\u00e9m com voc\u00ea ou voc\u00ea foi sozinha\/sozinho? Seu cachorro te acompanhou na viagem?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos escrever sobre este importante momento da sua vida, que \u00e9 tamb\u00e9m um enorme passo para a humanidade. Antes de tudo, como voc\u00ea est\u00e1 se sentindo hoje, ao embarcar no foguete que o levar\u00e1 para Marte? Est\u00e1 feliz? Preocupado? E agora que seu foguete acabou de pousar, estes sentimentos mudaram? Que nome eles t\u00eam?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste seu primeiro dia em Marte, o que voc\u00ea prefere fazer? Podemos passear e reconhecer o lugar, ou coletar materiais interessantes que virmos pelo caminho, quem sabe montar nossa nova casa e fazer comida l\u00e1 dentro. N\u00f3s comeremos comida de astronauta ou em Marte tem macarr\u00e3o?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temos 30 minutos para escrever sobre tudo que est\u00e1 acontecendo neste dia marcante, seja do lado de fora da nave, seja do lado de dentro da gente. <strong>Imagine-se vivendo isso e registre tudo no seu caderno ou <a href=\"https:\/\/quindim.com.br\/blog\/escrever-a-mao-e-melhor-para-o-aprendizado\/\" target=\"_blank\" rel=\"noreferrer noopener\">folha de papel<\/a><\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh2\">2. <strong>PROFESSOR<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea tem uma professora ou professor favorito? Como ele se chama e quais aulas ela\/ele d\u00e1? Pois hoje a brincadeira \u00e9 escrever como se f\u00f4ssemos esta pessoa. Vamos cal\u00e7ar os sapatos dela\/dele, vestir suas roupas, assumir seu corte de cabelo e tom de voz para viver um dia no seu lugar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No seu texto, voc\u00ea vai <strong>escrever em primeira pessoa, que \u00e9 a forma com que escrevemos quando todas as a\u00e7\u00f5es de um texto acontecem com a gente mesmo<\/strong>. Vamos fingir com todas as for\u00e7as que n\u00e3o somos n\u00f3s mesmos, mas sim esta outra pessoa que escolhemos para a brincadeira.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"570\" height=\"410\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/12\/Como-despertar-a-escrita-criativa-nas-criancas-meio2.jpg\" alt=\"Como despertar a escrita criativa nas crian\u00e7as\" class=\"wp-image-56349\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/12\/Como-despertar-a-escrita-criativa-nas-criancas-meio2.jpg 570w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/12\/Como-despertar-a-escrita-criativa-nas-criancas-meio2-150x108.jpg 150w\" sizes=\"(max-width: 570px) 100vw, 570px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">&#8220;A aula de hoje no 4\u00baB foi terr\u00edvel!&#8221;, voc\u00ea pode come\u00e7ar escrevendo, antes de contar que alguns alunos (que n\u00e3o vamos dizer o nome porque somos muito corretos) fizeram a maior bagun\u00e7a do ano, soprando bolinhas de papel com cuspe no teto da sala de aula. Voc\u00ea conversou com eles? Como fez para mostrar que aquela baderna n\u00e3o era legal?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seu texto tamb\u00e9m pode ser sobre a linda formatura que seus alunos organizaram. Voc\u00ea estava l\u00e1 presente assistindo tudo e, com muita emo\u00e7\u00e3o, entregou todos os diplomas a cada um dos estudantes que agora v\u00e3o para outra unidade do col\u00e9gio. Voc\u00ea sentir\u00e1 falta deles? O que eles faziam que voc\u00ea adorava? E o que eles faziam que voc\u00ea n\u00e3o achava legal e n\u00e3o sentir\u00e1 a menor falta?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como voc\u00ea se sente sendo uma\/um profissional t\u00e3o importante para tantas pessoas? \u00c9 legal ser um adulto assim fundamental para todos?<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh2\">3. <strong>DI\u00c1RIO DE F\u00c9RIAS<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Em um caderno que pode ser novo ou reaproveitado dos anos anteriores, voc\u00ea vai criar o Di\u00e1rio das F\u00e9rias. Todos os dias, registre nele o que aconteceu em casa, nos passeios que talvez voc\u00ea possa dar ou na viagem que quem sabe voc\u00ea ter\u00e1 a oportunidade de curtir. Aqui, o importante \u00e9 saber que at\u00e9 mesmo as coisas que parecem muito triviais tamb\u00e9m merecem ir para o di\u00e1rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caiu um meteoro no seu quintal? Incr\u00edvel, escreva a respeito no caderno! Tinha arroz com feij\u00e3o no almo\u00e7o e os adultos ficaram o dia todo ocupados sem tirar os olhos do computador? Pois \u00e9, isso tamb\u00e9m precisa ser registrado no Di\u00e1rio de F\u00e9rias, mesmo que pare\u00e7a n\u00e3o ter absolutamente gra\u00e7a nenhuma. Vale escrever sobre o que voc\u00ea viu, o que voc\u00ea sentiu, o que voc\u00ea falou e fez. Algu\u00e9m visitou sua casa ou voc\u00ea foi at\u00e9 a vov\u00f3? Anote a conversa que voc\u00eas tiveram naquele formato de di\u00e1logo, com travess\u00f5es, interroga\u00e7\u00f5es e tudo mais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pode ser que seu di\u00e1rio, ao final das f\u00e9rias, esteja bem parecido com um livro.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veja tamb\u00e9m: <a href=\"https:\/\/quindim.com.br\/blog\/a-importancia-do-tedio-para-saude\/\" target=\"_blank\" rel=\"noreferrer noopener\">A import\u00e2ncia do t\u00e9dio para a sa\u00fade e a criatividade<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh2\"><strong>4. HIST\u00d3RIA CL\u00c1SSICA RECONTADA<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Era uma vez a hist\u00f3ria que voc\u00ea mais gostava que sua m\u00e3e, pai, av\u00f3 ou professora contassem, e que, de tanto ouvir muitas e muitas vezes, voc\u00ea j\u00e1 at\u00e9 decorou tudo que acontece com todos os personagens. Ou era outra vez aquele filme legal pra caramba que voc\u00ea j\u00e1 assistiu tantas vezes que j\u00e1 decorou as falas de todas as atrizes e atores, que sabe as dancinhas e m\u00fasicas, e que gosta de rever sempre que n\u00e3o consegue escolher algo novo no streaming.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoje, vamos pegar esta hist\u00f3ria que voc\u00ea conhece de cor e salteado e vamos recont\u00e1-la. D\u00e1 para fazer isso de v\u00e1rias maneiras, e aqui v\u00e3o algumas sugest\u00f5es: em vez de se dar bem, o mocinho perde tudo no final; quem acabava a hist\u00f3ria triste agora vai acabar feliz, e vice-versa; vamos acrescentar mais um personagem novo \u00e0 hist\u00f3ria e ele vai ser superimportante nela; vamos eliminar algum personagem, e ver como a hist\u00f3ria se vira para acontecer sem ele.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nesta proposta de brincadeira, voc\u00ea pode inventar tudo na cabe\u00e7a, contar em voz alta para sua fam\u00edlia, e s\u00f3 depois passar as inven\u00e7\u00f5es para o papel<\/strong>. Assim talvez fique mais f\u00e1cil de deixar tudo bem redondinho na vers\u00e3o final.<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh2\">5. <strong>ADJETIVOS<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Adjetivos s\u00e3o as palavras que usamos para dar caracter\u00edsticas \u00e0s coisas e pessoas. Caracter\u00edsticas n\u00e3o s\u00e3o necessariamente boas ou ruins, qualidades ou defeitos \u2013 elas s\u00e3o o que s\u00e3o. Como quando um cachorro \u00e9 brincalh\u00e3o, quando um bolo est\u00e1 quente ou se algu\u00e9m se sente feliz ou triste.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pois neste exerc\u00edcio \u00e9 com os adjetivos que voc\u00ea vai trabalhar. Escreva um texto sobre qualquer assunto: pode ser uma hist\u00f3ria inventada, uma p\u00e1gina do seu Di\u00e1rio de F\u00e9rias, um relato dos seus sentimentos. Ou, se o dia n\u00e3o estiver muito bom para a criatividade, vale pegar uma hist\u00f3ria que j\u00e1 existe, escrita por outra pessoa \u2013 se escolher este formato, digite a hist\u00f3ria no computador ou escreva-a no papel.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/conteudo.quindim.com.br\/assinar-newsletter-banner-blog\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"810\" height=\"189\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/03\/Assine-o-Clube-de-Leitura-Quindim.jpg\" alt=\"Assine o Clube de Leitura Quindim\" class=\"wp-image-37877\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/03\/Assine-o-Clube-de-Leitura-Quindim.jpg 810w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/03\/Assine-o-Clube-de-Leitura-Quindim-768x179.jpg 768w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/03\/Assine-o-Clube-de-Leitura-Quindim-150x35.jpg 150w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Com essa hist\u00f3ria em m\u00e3os, vamos localizar todos os adjetivos que existem nela e apag\u00e1-los. <strong>Se tiver dificuldade, pe\u00e7a ajuda de um respons\u00e1vel ou educador<\/strong>. Com todos apagados, como sua hist\u00f3ria ficou? Voc\u00ea acha que ela ainda faz sentido?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se ela parece meio maluca, ou se parece que n\u00e3o vai ficar de p\u00e9 por muito tempo antes de desmoronar, vamos para a segunda parte da brincadeira. Sem colocar de volta os adjetivos antigos, mexa no seu texto para tentar fazer a hist\u00f3ria tornar a ser boa. Vale acrescentar novos adjetivos ou mesmo reescrever algumas partes sem usar essa classe de palavras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A ideia \u00e9 se divertir e abalar as estruturas da l\u00edngua!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gostou das ideias para incentivar a escrita criativa? Agora \u00e9 botar a m\u00e3o na massa! E, se voc\u00ea estiver procurando formas de estimular a criatividade infantil, o <a href=\"https:\/\/quindim.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clube de Leitura Quindim<\/a> tem um material que promete ajudar sua fam\u00edlia. <a href=\"https:\/\/conteudo.quindim.com.br\/livros-para-estimular-a-criatividade-infantil\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Acesse aqui<\/a> e baixe o guia gratuito do Quindim sobre 32 livros para estimular a criatividade infantil! Confira os benef\u00edcios da criatividade para os pequenos e veja as obras incr\u00edveis selecionadas!<\/p>\n\n\n\n<h2 class=\"wp-block-heading subtituloh2\">Estante Quindim<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Conhe\u00e7a 3 livros para ler com as crian\u00e7as e que pode incentiv\u00e1-las a fazer algumas das atividades de escrita criativa propostas neste artigo:<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"260\" height=\"241\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/01\/Livro-o-ponto.jpg\" alt=\"Livro o ponto\" class=\"wp-image-35513\" style=\"aspect-ratio:1;object-fit:contain;width:247px;height:auto\" title=\"\"><figcaption class=\"wp-element-caption\"><em><a href=\"https:\/\/quindim.com.br\/selecoes\/livro\/o-ponto\/peter-h.-reynolds\/9788546902804\" target=\"_blank\" rel=\"noreferrer noopener\">O ponto<\/a><\/em>, de Peter H. Reynolds<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"360\" height=\"508\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/10\/minhas-ferias-pula-uma-linha-paragrafo.jpg\" alt=\"Minhas f\u00e9rias, pula uma linha, par\u00e1grafo. (escritora Christiane Gribel, ilustrador de Jean-Claude R. Alphen e editora Salamandra).\" class=\"wp-image-33576\" style=\"aspect-ratio:1;object-fit:contain\" title=\"\"><figcaption class=\"wp-element-caption\"><em><a href=\"https:\/\/quindim.com.br\/selecoes\/livro\/minhas-ferias%2C-pula-uma-linha%2C-paragrafo\/christiane-gribel\/9788516085292\" target=\"_blank\" rel=\"noreferrer noopener\">Minhas f\u00e9rias, pula uma linha, par\u00e1grafo<\/a><\/em>, de Christiane Gribel<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img decoding=\"async\" width=\"405\" height=\"405\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/03\/ConteMaisUmaVezCapaTransparente-edited-1.png\" alt=\"Conte mais uma vez (autor Weberson Santiago, editora Yellowfante)\" class=\"wp-image-48682\" style=\"object-fit:contain;width:264px;height:264px\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/03\/ConteMaisUmaVezCapaTransparente-edited-1.png 405w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/03\/ConteMaisUmaVezCapaTransparente-edited-1-300x300.png 300w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/03\/ConteMaisUmaVezCapaTransparente-edited-1-150x150.png 150w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/03\/ConteMaisUmaVezCapaTransparente-edited-1-100x100.png 100w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/03\/ConteMaisUmaVezCapaTransparente-edited-1-24x24.png 24w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/03\/ConteMaisUmaVezCapaTransparente-edited-1-48x48.png 48w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/03\/ConteMaisUmaVezCapaTransparente-edited-1-96x96.png 96w\" sizes=\"(max-width: 405px) 100vw, 405px\" \/><figcaption class=\"wp-element-caption\"><em><a href=\"https:\/\/quindim.com.br\/selecoes\/livro\/conte-mais-uma-vez\/weberson-santiago\/9786588437193\" target=\"_blank\" rel=\"noreferrer noopener\">Conte mais uma vez<\/a><\/em>, de Weberson Santiago<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Todo mundo sabe escrever! Conhe\u00e7a algumas propostas divertidas de exerc\u00edcios de escrita criativa para trabalhar em sala de aula ou em casa durante as f\u00e9rias escolares!<\/p>\n","protected":false},"author":79,"featured_media":56345,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[2338,505],"tags":[],"class_list":["post-56335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atividades-e-brincadeiras","category-familia"],"acf":{"posts_relacionados":[15224,52745,46511]},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/56335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/comments?post=56335"}],"version-history":[{"count":0,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/56335\/revisions"}],"acf:post":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/46511"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/52745"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/15224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media\/56345"}],"wp:attachment":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media?parent=56335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/categories?post=56335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/tags?post=56335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}