{"id":46483,"date":"2022-11-20T21:20:26","date_gmt":"2022-11-21T00:20:26","guid":{"rendered":"https:\/\/quindim.com.br\/blog\/?p=46483"},"modified":"2025-05-21T05:53:38","modified_gmt":"2025-05-21T08:53:38","slug":"literatura-infantil-na-flip-2022","status":"publish","type":"post","link":"https:\/\/quindim.com.br\/blog\/literatura-infantil-na-flip-2022\/","title":{"rendered":"Literatura infantil na Flip 2022"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Retomando as ruas e pra\u00e7as de Paraty (RJ), a Festa Liter\u00e1ria de Paraty (Flip) celebra seus 20 anos e retorna \u00e0 sua programa\u00e7\u00e3o presencial. O evento ocorrer\u00e1 entre os dias 23 e 27 de novembro (<a href=\"https:\/\/www.flip.org.br\/flip-2022\/programa-principal\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">consulte a programa\u00e7\u00e3o oficial<\/a>). E, para discutir literatura infantil, caminhos e tend\u00eancias, a Casa Libre e Graviola Digital promover\u00e1 uma s\u00e9rie de mesas durante todo o per\u00edodo. Com a j\u00e1 tradicional curadoria do Clube de Leitura Quindim, que ocorre desde 2018, os temas fogem da obviedade e abordam assuntos atuais que refletem preocupa\u00e7\u00f5es do cen\u00e1rio editorial e criativo brasileiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A programa\u00e7\u00e3o se concentra pela manh\u00e3, com duas rodas de conversa por dia, de quinta a domingo. Elas ser\u00e3o transmitidas ao vivo pelo Instagram do Clube Quindim e ficar\u00e3o dispon\u00edveis no<a href=\"https:\/\/www.youtube.com\/@ClubeQuindim\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"> canal do Youtube (@clubequindim)<\/a>. Segundo Lara Kouzmin-Korovaeff, diretora de eventos da Libre, os encontros t\u00eam como objetivo \u201cdiscutir tend\u00eancias e desafios que est\u00e3o na pauta de todos que trabalham com literatura voltada para a inf\u00e2ncia \u2013 autores, ilustradores, editores\u201d. Para Renata Nakano, idealizadora do Clube Quindim, \u201ca Casa Libre e Graviola Digital \u00e9 um dos \u00fanicos espa\u00e7os, sen\u00e3o o \u00fanico, a promover reflex\u00f5es sobre a literatura infantil em uma das mais prestigiosas festas liter\u00e1rias do Brasil. Enquanto as demais atividades que abra\u00e7am a literatura infantil se destinam \u00e0s crian\u00e7as, a Casa Libre e Graviola Digital tornou-se um ponto de encontro anual entre as pessoas que trabalham e pensam a literatura infantil no Brasil\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"570\" height=\"410\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/11\/Literatura-infantil-na-Flip-2022.jpg\" alt=\"\" class=\"wp-image-46493\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/11\/Literatura-infantil-na-Flip-2022.jpg 570w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/11\/Literatura-infantil-na-Flip-2022-150x108.jpg 150w\" sizes=\"(max-width: 570px) 100vw, 570px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"subtituloh2 wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\">Confira a programa\u00e7\u00e3o<\/mark><\/mark><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>24\/11 | quinta<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">11h30 | Modismos na ilustra\u00e7\u00e3o e coloniza\u00e7\u00e3o est\u00e9tica, com Gra\u00e7a Lima (ilustradora e professora da UFRJ), Raquel Matsushita (autora) e Renata Nakano (Clube Quindim)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>25\/11 | sexta<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">10h | Livros ilustrados: para classe m\u00e9dia ver?, com Dani Gutfreund (Lugar de Ler) e Denise Guilherme (A Taba)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11h30 | O livro infantil, <em>dumping<\/em> e as pequenas livrarias, com Lizandra Magon de Almeida (Janda\u00edra), Maria Carolina Borin (consultora) e Martha Ribas (Livraria Janela)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>26\/11 | s\u00e1bado<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">10h | As independentes lan\u00e7ando tend\u00eancias, com Isabel Malzoni (Caixote), Thaisa Burani (Cai-Cai), Cris Warth (Pallas) e Cassia Bittens (PUC-SP)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11h30 | Meio ambiente al\u00e9m do lugar comum: uma vis\u00e3o decolonizadora, com Dipacho (autor), Andr\u00e9s Sandoval (autor), Lara Kouzmin-Korovaeff (Semente e Pingo de Luz) e Renata Nakano (Clube Quindim)<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>27\/11 | domingo<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">10h | Literatura e alteridade: a po\u00e9tica do deslocamento, com Jana\u00edna de Figueiredo (autora) e Gabriela Romeu (autora)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">11h30 | Encerramento: Performance de ilustra\u00e7\u00e3o com artistas convidados<\/p>\n\n\n\n<h2 class=\"subtituloh2 wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><strong>Sobre a Libre<\/strong><\/mark><\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Reunindo mais de 170 editores independentes brasileiros, a Libre foi fundada em 2002 e tem por miss\u00e3o promover a bibliodiversidade do mercado editorial brasileiro, com o fortalecimento do neg\u00f3cio independente de edi\u00e7\u00e3o de livros. Para isso, promove a\u00e7\u00f5es e discuss\u00f5es para a amplia\u00e7\u00e3o do p\u00fablico leitor, fortalecimento das empresas editoras independentes e cria\u00e7\u00e3o e implementa\u00e7\u00e3o de pol\u00edticas p\u00fablicas em favor do livro e da leitura.<\/p>\n\n\n\n<h2 class=\"subtituloh2 wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><strong>Sobre o Clube Quindim<\/strong><\/mark><\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O Clube de Leitura Quindim \u00e9 um clube de assinatura de livros infantis, que reuniu o time dos sonhos para selecionar e levar literatura transformadora a crian\u00e7as de todo o Brasil. J\u00e1 s\u00e3o mais de 15 mil crian\u00e7as impactadas em todos os estados brasileiros, chegando a 1500 cidades e entregando mais de 250 mil exemplares de livros transformadores que desenvolvem n\u00e3o apenas o autoconhecimento, o pensamento cr\u00edtico e aut\u00f4nomo, mas tamb\u00e9m aquilo que nos faz mais humanos: o afeto e a empatia. Saiba mais em: <a href=\"http:\/\/quindim.com.br\" target=\"_blank\" rel=\"noreferrer noopener\">quindim.com.br<\/a>.<\/p>\n\n\n\n<h2 class=\"subtituloh2 wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\">Servi\u00e7o<\/mark><\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Evento: Feira Liter\u00e1ria de Paraty (Flip) 2022 \u2013 Programa\u00e7\u00e3o Literatura Infantil<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando: 23 a 27 de novembro de 2022<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Local: Casa Libre (Rua da Lapa, 200 \u2013 Centro Hist\u00f3rico de Paraty)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ingressos: Gratuito, mediante lota\u00e7\u00e3o<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"http:\/\/quindim.com.br\"><img decoding=\"async\" width=\"810\" height=\"189\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/04\/O-melhor-clube-de-assinatura-infantil.gif\" alt=\"O melhor clube de assinatura infantil\" class=\"wp-image-38466\" title=\"\"><\/a><\/figure>\n<\/div><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Realizada pela Libre, com patroc\u00ednio da Graviola Digital e da Forma Certa, e curadoria do Clube de Leitura Quindim, programa\u00e7\u00e3o discutir\u00e1 caminhos e tend\u00eancias da literatura infantil.<\/p>\n","protected":false},"author":8,"featured_media":3019,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[499,509,513,497],"tags":[],"class_list":["post-46483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatura-infantil","category-cultura","category-datas-especiais","category-livros-infantis"],"acf":{"posts_relacionados":""},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/46483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/comments?post=46483"}],"version-history":[{"count":0,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/46483\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media\/3019"}],"wp:attachment":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media?parent=46483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/categories?post=46483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/tags?post=46483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}