{"id":3656,"date":"2019-10-04T11:50:26","date_gmt":"2019-10-04T14:50:26","guid":{"rendered":"https:\/\/blog.clubequindim.com.br\/?p=3656"},"modified":"2021-10-05T17:17:48","modified_gmt":"2021-10-05T20:17:48","slug":"trem-de-ferro","status":"publish","type":"post","link":"https:\/\/quindim.com.br\/blog\/trem-de-ferro\/","title":{"rendered":"Conhe\u00e7a a obra que trata de um \u00edcone da cultura brasileira"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Um trem que cruza pontes, passa por postes, pastos, galhos, boiadas. Um trem que atravessa o pa\u00eds, mostrando aos passageiros a mistura de cores das paisagens pelas janelas. \u00c9 esse trem que o poeta Manuel Bandeira descreve no poema <em>Trem de Ferro<\/em>, um cl\u00e1ssico da cultura brasileira. A obra foi selecionada pela curadoria do <a rel=\"noreferrer noopener\" aria-label=\"Clube Quindim (opens in a new tab)\" href=\"https:\/\/www.clubequindim.com.br\/\" target=\"_blank\">Clube Quindim<\/a> para este m\u00eas, em uma edi\u00e7\u00e3o ilustrada por Gian Calvi, e certamente vai fascinar os pequenos com suas imagens e com a sonoridade dos versos criados por Bandeira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nascido em Recife em 1886, o poeta foi um dos principais nomes do movimento modernista brasileiro, tanto que seu poema <em>Os Sapos<\/em> abriu a Semana de Arte Moderna de 1922. Sua <a rel=\"noreferrer noopener\" aria-label=\"poesia (opens in a new tab)\" href=\"https:\/\/blog.clubequindim.com.br\/10-poemas-para-crianca-amar-poesia\/\" target=\"_blank\">poesia<\/a> \u00e9 simples e direta, retrata caracter\u00edsticas da cultura brasileira e a busca pela alegria de viver \u2013 Bandeira era tuberculoso e, portanto, lidava com a perspectiva constante da morte. Era, ainda, cr\u00edtico, professor e tradutor, tendo sido eleito para a Academia Brasileira de Letras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seu poema <em>Trem de Ferro<\/em> foi publicado pela primeira vez em 1936, no livro <em>Estrela da manh\u00e3<\/em>. Ele narra, de forma coloquial, cenas vistas da janela de um trem da \u00e9poca, e tem um ritmo e uma musicalidade que realmente nos transportam para uma viagem de trem. N\u00e3o \u00e0 toa a obra foi musicada por dois grandes nomes da m\u00fasica nacional: Villa-Lobos e Ant\u00f4nio Carlos Jobim. Mas n\u00e3o foram s\u00f3 eles que se encantaram por esse s\u00edmbolo: se olharmos atentamente para nosso repert\u00f3rio musical, h\u00e1 muitos trens marcantes.<\/p>\n\n\n\n<h2 class=\"subtituloh2 wp-block-heading\"><span style=\"color:#f27059\" class=\"has-inline-color\"><span style=\"color:#f27059\" class=\"has-inline-color\">O trem no imagin\u00e1rio brasileiro <\/span><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Da cl\u00e1ssica maria-fuma\u00e7a aos modernos metr\u00f4s, o trem parece permear nosso imagin\u00e1rio e despertar fasc\u00ednio \u2013 voc\u00ea j\u00e1 percebeu a rea\u00e7\u00e3o das crian\u00e7as diante de um trem? \u00c9 not\u00e1vel! Na m\u00fasica brasileira n\u00e3o \u00e9 diferente. O trem est\u00e1 bem paulistano no ic\u00f4nico <em>Trem das Onze<\/em>, do sambista Adoniran Barbosa, observando paisagens, chegadas e partidas em <em>Trem das Sete<\/em>, de Raul Seixas, e ainda carregado de esperan\u00e7a, amor e verdade em <em>O Trem<\/em>, de Gonzaguinha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na realidade do pa\u00eds, entretanto, o trem n\u00e3o \u00e9 t\u00e3o presente quanto poderia. O Brasil tem cerca de 30 mil quil\u00f4metros de extens\u00e3o de malha ferrovi\u00e1ria -\u2013 a t\u00edtulo de compara\u00e7\u00e3o, a R\u00fassia tem 87 mil quil\u00f4metros e a China 86 mil. At\u00e9 os anos 1950, o trem era visto como um \u00edcone para o transporte de carga pelo territ\u00f3rio nacional. No entanto, a partir desse per\u00edodo, passou-se a dar \u00eanfase ao desenvolvimento rodovi\u00e1rio no pa\u00eds, principalmente pelo desejo de gerar uma expans\u00e3o econ\u00f4mica r\u00e1pida naquela d\u00e9cada. Hoje, 65% do transporte de cargas \u00e9 feito por caminh\u00f5es, ainda que a capacidade dos vag\u00f5es de trens seja maior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De qualquer forma, em muitas cidades brasileiras, \u00e9 poss\u00edvel ver trens cruzando morros, pastos e cidades, e at\u00e9 levar os pequenos para um passeio de maria-fuma\u00e7a. \u00c9 uma experi\u00eancia encantadora que certamente ficar\u00e1 na lembran\u00e7a.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Alunos do 1\u00ba Ano matutino apresentam &quot;Trem de ferro - Manuel Bandeira&quot;\" width=\"810\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/ebicRgwfp3o?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption>Interpreta\u00e7\u00e3o dos alunos da escola Chave do Saber para a obra que o Quindim entregar\u00e1 em outubro, <em>Trem de Ferro<\/em>, de Manuel Bandeira.<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-columns bloco-cta has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#fdb813\">\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/quindim.com.br\/\"><img decoding=\"async\" width=\"434\" height=\"195\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2020\/07\/call01.png\" alt=\"Assine o Clube Quindim\" class=\"wp-image-9392\" title=\"\"><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column bloco-cta-direita is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center titulo-cta wp-block-paragraph\"><span style=\"color:#f27059\" class=\"has-inline-color\">APROVEITE ESTE MOMENTO PARA INCENTIVAR A LEITURA!<\/span><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100 botao-cta is-style-fill\"><a class=\"wp-block-button__link\" href=\"https:\/\/quindim.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color:#e3e2e2\" class=\"has-inline-color\">ASSINE O CLUBE QUINDIM E RECEBA OS MELHORES LIVROS INFANTIS!<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Um trem que cruza pontes, passa por postes, pastos, galhos, boiadas. Um trem que atravessa o pa\u00eds, mostrando aos passageiros a mistura de cores das paisagens pelas janelas. \u00c9 esse trem que o poeta Manuel Bandeira descreve no poema Trem de Ferro, um cl\u00e1ssico da cultura brasileira. A obra foi selecionada pela curadoria do Clube [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":3660,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[509,513,499],"tags":[],"class_list":["post-3656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-datas-especiais","category-literatura-infantil"],"acf":{"posts_relacionados":[23861,19035,28851]},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/3656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3656"}],"version-history":[{"count":0,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/3656\/revisions"}],"acf:post":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/28851"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/19035"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/23861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media\/3660"}],"wp:attachment":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}