{"id":3506,"date":"2019-09-11T14:56:29","date_gmt":"2019-09-11T17:56:29","guid":{"rendered":"https:\/\/blog.clubequindim.com.br\/?p=3506"},"modified":"2021-12-29T12:25:36","modified_gmt":"2021-12-29T15:25:36","slug":"ditadura-da-felicidade","status":"publish","type":"post","link":"https:\/\/quindim.com.br\/blog\/ditadura-da-felicidade\/","title":{"rendered":"Ditadura da felicidade: o que h\u00e1 por tr\u00e1s desse mal do nosso tempo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00c0s vezes o sol est\u00e1 brilhando da janela para fora, mas, dentro da gente, a sensa\u00e7\u00e3o \u00e9 de c\u00e9u nublado. Nem sempre precisa ter acontecido alguma coisa: a vida pode at\u00e9 estar correndo nos trilhos, sem grandes problemas, mas a verdade \u00e9 que isso n\u00e3o \u00e9 suficiente para evitar sentimentos de tristeza e mau humor. A alegria n\u00e3o \u00e9 um estado que nos acompanha constantemente, o que \u00e9 profundamente opressor, j\u00e1 que, hoje, parecemos estar imersos em uma ditadura da felicidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esse tema t\u00e3o atual e t\u00e3o urgente perpassa um dos livros que a sele\u00e7\u00e3o do <a rel=\"noreferrer noopener\" aria-label=\"Clube Quindim (opens in a new tab)\" href=\"https:\/\/www.clubequindim.com.br\/\" target=\"_blank\">Clube Quindim<\/a> separou para seus assinantes neste m\u00eas de setembro. Trata-se do t\u00edtulo <em>Tr\u00eas desejos para o sr. Pug<\/em>, de Sebastian Meschenmoser. Nele, o sr. Pug acorda tarde e mal-humorado, sentimento que piora quando ele percebe que n\u00e3o h\u00e1 cereal, caf\u00e9 ou leite em sua casa, que est\u00e1 chovendo e o jornal est\u00e1 arruinado. A sensa\u00e7\u00e3o \u00e9 de que era melhor nem ter sa\u00eddo da cama at\u00e9 que uma fada empolgada, disposta a fazer de tudo para ver sr. Pug feliz, aparece.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas ser\u00e1 que precisamos sempre estar de bom humor? Ser\u00e1 que os sentimentos ditos ruins tamb\u00e9m n\u00e3o fazem parte da vida? E mais: ser\u00e1 que outra pessoa pode se responsabilizar por nosso bem-estar? Essas s\u00e3o algumas perguntas que essa hist\u00f3ria nos convida a fazer \u2013 e que t\u00eam tudo a ver com o contexto em que estamos inseridos.<\/p>\n\n\n\n<h2 class=\"subtituloh2 wp-block-heading\"><span style=\"color:#f27059\" class=\"has-inline-color\"><span style=\"color:#f27059\" class=\"has-inline-color\">Sociedade de consumo: alegria a um passo de dist\u00e2ncia <\/span><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Muitos dos comportamentos que temos s\u00e3o fruto da cultura de consumo em que estamos inseridos. Para Isleide Fontenelle, autora do livro \u201cCultura de Consumo\u201d, essa tend\u00eancia teve sua primeira fase no final do s\u00e9culo XIX e come\u00e7o do s\u00e9culo XX, quando foram criados os mercados nacionais, a produ\u00e7\u00e3o em grande escala, a inven\u00e7\u00e3o do marketing e do consumidor moderno. A partir da\u00ed, temos o surgimento de uma l\u00f3gica de consumo: comprar um item n\u00e3o \u00e9 apenas adquirir um produto ou servi\u00e7o, \u00e9 definir uma identidade, satisfazer um desejo, ser quem se quer ser e ainda sentir o que se quer sentir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoje, com a tecnologia, a cultura de consumo est\u00e1 muito fortalecida: nos tornamos mais hedonistas, consumistas e imediatistas. A um toque do dedo no celular podemos comprar o que quisermos em qualquer lugar do mundo. Al\u00e9m disso, o consumo se torna ainda mais pr\u00f3ximo da ideia da felicidade, como se fazer determinada viagem, ter o carro da moda, as roupas que a influenciadora usa ou o corpo que a celebridade tem pudessem ser um passe para a alegria verdadeira. Com tantas op\u00e7\u00f5es supostamente acess\u00edveis, \u00e9 quase proibido estar triste, o que fortalece essa ideia de ditadura da felicidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As redes sociais parecem ter turbinado essa opress\u00e3o. Para <a href=\"https:\/\/blogs.oglobo.globo.com\/gente-boa\/post\/instagram-criou-uma-ditadura-da-felicidade-diz-antropologo-535665.html\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Octavio Bonet<\/a>, doutor em Antropologia da Sa\u00fade, o Instagram, entre outras plataformas de m\u00eddias sociais, contribui para a cria\u00e7\u00e3o da ditadura da felicidade, em que \u201ctodos devem estar vivendo momentos maravilhosos o tempo todo\u201d. A psic\u00f3loga Erika Maracaba fala em \u201cpositividade t\u00f3xica\u201d, uma \u201ctirania da positividade\u201d, que nos induz a ignorar ou bloquear sentimentos de tristeza para estarmos sempre felizes. Em um texto, ela comenta: \u201cFelicidade compuls\u00f3ria \u00e9 forte combust\u00edvel para a infelicidade\u201d. Ainda lembra que todos os sentimentos t\u00eam sua import\u00e2ncia, e quanto mais s\u00e3o ignorados, mais perdemos nossa habilidade de lidar com eles.<\/p>\n\n\n\n<h2 class=\"subtituloh2 wp-block-heading\"><span style=\"color:#f27059\" class=\"has-inline-color\"><span style=\"color:#f27059\" class=\"has-inline-color\">Tristeza X depress\u00e3o <\/span><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se por um lado, parece ser padr\u00e3o esperar que as pessoas estejam sempre esbanjando felicidade, por outro, um estado de tristeza comumente passa a ser associado com depress\u00e3o. Para o sanitarista Paulo Amarante, professor e pesquisador da Escola Nacional de Sa\u00fade P\u00fablica Sergio Arouca (Laps\/Ensp\/Fiocruz) e presidente\u00a0<em>honoris causa<\/em> da Associa\u00e7\u00e3o Brasileira de Sa\u00fade Mental (Abrasme), a depress\u00e3o se tornou um conceito male\u00e1vel, aplicado a diversas situa\u00e7\u00f5es de vida, como rea\u00e7\u00f5es a lutos, separa\u00e7\u00f5es e desemprego. Com esse diagn\u00f3stico sendo distribu\u00eddo com maior abrang\u00eancia, cresce tamb\u00e9m a indica\u00e7\u00e3o de antidepressivos, medicamentos que geram depend\u00eancia reconhecida pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade e devem ser prescritos com muita cautela, mediante avalia\u00e7\u00e3o de um profissional de confian\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paulo diz: \u201cA vida n\u00e3o \u00e9 uma norma, h\u00e1 diferentes padr\u00f5es, cada vida \u00e9 muito pessoal. Podemos inventar a doen\u00e7a, ampliar o conceito de doen\u00e7a e patologizar todo o sofrimento, ou podemos inventar e ampliar o conceito de sa\u00fade. O normal n\u00e3o \u00e9 o estado de bem-estar eterno, permanente, ideal. O normal \u00e9 a capacidade de rea\u00e7\u00e3o \u00e0s adversidades \u2013 pois elas existem\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o especialista, podemos dizer que h\u00e1 depress\u00e3o quando uma situa\u00e7\u00e3o foge \u00e0 explica\u00e7\u00e3o racional, quando h\u00e1 um estado de tristeza profunda inexplic\u00e1vel, com perda de \u00e2nimo, ideias de desvaloriza\u00e7\u00e3o e autodestrui\u00e7\u00e3o, sem que houvesse um fato disparador, como uma perda. Um estado muito diferente, portanto, do sentimento de tristeza e mau humor que acomete a todos n\u00f3s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outro ponto importante \u00e9 compreender que processos de perda e morte, por exemplo, s\u00e3o encarados de forma diversas por culturas diversas. Paulo menciona que o \u201cManual Diagn\u00f3stico e Estat\u00edstico de Transtornos Mentais\u201d, da Associa\u00e7\u00e3o Americana de Psiquiatria, considera que o luto a partir de seis meses de dura\u00e7\u00e3o deve ser considerado patol\u00f3gico. Entretanto, \u00e9 preciso compreender que cada pessoa viver\u00e1 esse processo de uma maneira: \u201cEsse \u00e9 um crit\u00e9rio absurdo; como se o luto fosse comum em todas as sociedades e culturas. Os bororo fazem um ritual muito diferente do das vi\u00favas espanholas, de origem latina. Minha m\u00e3e ficou um ano de preto, quando meu pai faleceu. N\u00e3o era um processo individual, era cultural tamb\u00e9m\u201d.<\/p>\n\n\n\n<h2 class=\"subtituloh2 wp-block-heading\"><span style=\"color:#f27059\" class=\"has-inline-color\"><span style=\"color:#f27059\" class=\"has-inline-color\">Combatendo a ditadura da felicidade <\/span><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Com todo esse cen\u00e1rio, \u00e9 normal que os pais levem essas preocupa\u00e7\u00f5es para as suas rela\u00e7\u00f5es com os filhos. Diante das crian\u00e7as, espera-se ainda mais ver muitos sorrisos e aquela alegria efusiva associada \u00e0 inf\u00e2ncia. No entanto, para al\u00e9m das normas e das expectativas sociais que caem sobre todos n\u00f3s, tentar enxergar a personalidade e compreender o processo de cada indiv\u00edduo parece ser o caminho mais equilibrado e mais acolhedor para todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 importante estar atento a mudan\u00e7as de comportamento dos pequenos e \u00e0 falta de \u00e2nimo que Paulo Amarante relata, assim como dialogar com as crian\u00e7as e introduzi-las a um processo de <a href=\"https:\/\/blog.clubequindim.com.br\/5-livros-infantis-que-vao-ajudar-seu-filho-a-lidar-com-as-emocoes\/\" target=\"_blank\" rel=\"noreferrer noopener\">alfabetiza\u00e7\u00e3o emocional<\/a>, reconhecimento dos pr\u00f3prios sentimentos. No caso da tristeza, vale pensar no simp\u00e1tico filme <em>Divertidamente<\/em>, da Pixar. A partir do amadurecimento de uma menininha, ele apresenta as emo\u00e7\u00f5es que habitam as pessoas: a alegria, a raiva, o nojo, o medo e a tristeza. Com o passar do filme, fica claro que, \u00e0 medida que a personagem cresce, os sentimentos ficam mais complexos. Assim, ficar triste n\u00e3o \u00e9 completamente ruim, mas \u00e9 um processo importante para amadurecer, se conhecer melhor e at\u00e9 acessar momentos alegres depois. A vida, afinal, \u00e9 feita de complexidades, e ensinar isso \u00e0s crian\u00e7as desde o in\u00edcio da vida pode ser uma boa maneira de fortalec\u00ea-las para os desafios do futuro.<\/p>\n\n\n\n<div class=\"wp-block-columns bloco-cta has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#fdb813\">\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/quindim.com.br\/\"><img decoding=\"async\" width=\"434\" height=\"195\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2020\/07\/call01.png\" alt=\"Assine o Clube Quindim\" class=\"wp-image-9392\" title=\"\"><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column bloco-cta-direita is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center titulo-cta wp-block-paragraph\"><span style=\"color:#f27059\" class=\"has-inline-color\">APROVEITE ESTE MOMENTO PARA INCENTIVAR A LEITURA!<\/span><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100 botao-cta is-style-fill\"><a class=\"wp-block-button__link\" href=\"https:\/\/quindim.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color:#e3e2e2\" class=\"has-inline-color\">ASSINE O CLUBE QUINDIM E RECEBA OS MELHORES LIVROS INFANTIS!<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>\u00c0s vezes o sol est\u00e1 brilhando da janela para fora, mas, dentro da gente, a sensa\u00e7\u00e3o \u00e9 de c\u00e9u nublado. Nem sempre precisa ter acontecido alguma coisa: a vida pode at\u00e9 estar correndo nos trilhos, sem grandes problemas, mas a verdade \u00e9 que isso n\u00e3o \u00e9 suficiente para evitar sentimentos de tristeza e mau humor. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":3511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[514],"tags":[],"class_list":["post-3506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao-familia"],"acf":{"posts_relacionados":[14973,14588,16384]},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/3506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3506"}],"version-history":[{"count":0,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/3506\/revisions"}],"acf:post":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/16384"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/14588"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/14973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media\/3511"}],"wp:attachment":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}