{"id":25680,"date":"2022-08-10T15:30:00","date_gmt":"2022-08-10T18:30:00","guid":{"rendered":"https:\/\/quindim.com.br\/blog\/?p=25680"},"modified":"2025-06-30T12:56:52","modified_gmt":"2025-06-30T15:56:52","slug":"como-contar-historias-para-bebes","status":"publish","type":"post","link":"https:\/\/quindim.com.br\/blog\/como-contar-historias-para-bebes\/","title":{"rendered":"Quando come\u00e7ar e como contar hist\u00f3rias para beb\u00eas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Qual o momento ideal para come\u00e7ar a ler para sua crian\u00e7a? E mais: como contar hist\u00f3rias para beb\u00eas? Embora n\u00e3o haja um consenso ou uma resposta definitiva, nossa dica \u00e9: <strong>comece a ler com seu filho ou filha desde cedo<\/strong>, se poss\u00edvel, durante a gesta\u00e7\u00e3o. A partir do 5\u00ba m\u00eas, os pequenos j\u00e1 conseguem ouvir sons de fora da barriga, come\u00e7am a reconhecer a voz dos pais e podem reagir a est\u00edmulos sonoros. Por isso, muitos pediatras incentivam a <a href=\"https:\/\/quindim.com.br\/blog\/leitura-para-bebes-na-barriga\/\" target=\"_blank\" rel=\"noreferrer noopener\">leitura na gravidez<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas tenha em mente que nunca \u00e9 tarde para come\u00e7ar! Ap\u00f3s o nascimento, voc\u00ea pode contar hist\u00f3rias para beb\u00eas e observar sua rea\u00e7\u00e3o no momento da leitura. Embora os menorzinhos n\u00e3o compreendam o significado de todas as palavras num primeiro momento, eles estar\u00e3o assimilando os tons, os ritmos, o olhar de quem l\u00ea para eles. Aos poucos, voc\u00ea est\u00e1 incentivando a cria\u00e7\u00e3o de um h\u00e1bito de leitura com sua fam\u00edlia e criando uma jornada para um futuro leitor. Ent\u00e3o, que tal come\u00e7ar a ler com seu beb\u00ea hoje mesmo?<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/quindim.com.br\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"770\" height=\"200\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_IdadeFilho.jpg\" alt=\"Clube Quindim\" class=\"wp-image-64970\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_IdadeFilho.jpg 770w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_IdadeFilho-768x199.jpg 768w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_IdadeFilho-150x39.jpg 150w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading subtituloh2\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><strong>Como escolher livros para beb\u00eas<\/strong><\/mark><\/mark>?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">H\u00e1 muitas op\u00e7\u00f5es de livros para beb\u00eas no mercado, e \u00e9 comum que pais e cuidadores fiquem em d\u00favida sobre o que ler e acabem optando apenas pelos<a href=\"https:\/\/quindim.com.br\/blog\/livros-cartonados-livros-de-pano-e-livros-interativos\/\"> livros sensoriais, de pano ou livros-brinquedo<\/a>. Mas saiba que as obras para beb\u00eas podem ter muitas formas, textos mais longos, mais curtos, ilustra\u00e7\u00f5es coloridas, s\u00f3brias ou apenas em preto e branco. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1170\" height=\"730\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/08\/Como-contar-historias-para-bebes-1-1170x730.jpg\" alt=\"\" class=\"wp-image-43859\" style=\"width:574px;height:auto\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/08\/Como-contar-historias-para-bebes-1.jpg 1170w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/08\/Como-contar-historias-para-bebes-1-768x479.jpg 768w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/08\/Como-contar-historias-para-bebes-1-150x94.jpg 150w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\"><em>Foto: Canva<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Nos primeiros meses de vida, inclusive, a vis\u00e3o dos beb\u00eas ainda est\u00e1 em desenvolvimento, por isso, livros com cores contrastantes s\u00e3o uma boa op\u00e7\u00e3o. Mas, claro, n\u00e3o fique preso a eles. H\u00e1 uma grande diversidade de estilos de ilustra\u00e7\u00f5es para voc\u00eas explorarem juntos!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, obras com repeti\u00e7\u00f5es de estruturas textuais e elementos que fazem parte do dia a dia de um beb\u00ea costumam ser \u00f3timas escolhas para essa fase, j\u00e1 que nesse momento os pequenos est\u00e3o come\u00e7ando a ganhar vocabul\u00e1rio. Para ajudar nesse processo de fixa\u00e7\u00e3o de vocabul\u00e1rio, voc\u00ea pode ler os mesmos livros v\u00e1rias vezes com os pequenos. Com o tempo, as palavras presentes nessas hist\u00f3rias se tornar\u00e3o parte de seu repert\u00f3rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nossa dica principal \u00e9: <strong>escolha livros que prezem pela qualidade liter\u00e1ria. <\/strong>\u00c9 importante apresentar obras de diferentes estilos, est\u00e9ticas e com formas diversas de contar hist\u00f3rias. Isso \u00e9 essencial para aumentar o repert\u00f3rio dos pequenos. Afinal, <strong>a literatura n\u00e3o existe apenas para cumprir uma \u00fanica fun\u00e7\u00e3o no desenvolvimento da crian\u00e7a<\/strong>. Ela ajuda a aumentar o vocabul\u00e1rio e o est\u00edmulo visual sim, mas tamb\u00e9m traz o potencial de ampliar nosso mundo, levantar reflex\u00f5es, nos divertir e muito mais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quer dicas do que ler com seu beb\u00ea? Preparamos um material gratuito para voc\u00ea conhecer 30 obras diversificadas para os beb\u00eas.<\/p>\n\n\n\n<div id=\"wisepops-embed-container-30-livros\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/conteudo.quindim.com.br\/assinar-newsletter-banner-blog\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"770\" height=\"200\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_RecebaDicas.jpg\" alt=\"\" class=\"wp-image-64972\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_RecebaDicas.jpg 770w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_RecebaDicas-768x199.jpg 768w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_RecebaDicas-150x39.jpg 150w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading subtituloh2\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><strong>Como um clube de leitura para beb\u00ea pode ajudar?<\/strong><\/mark><\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Uma forma pr\u00e1tica de encontrar boas obras para beb\u00eas \u00e9 assinar o <a href=\"https:\/\/quindim.com.br\/?utm_source=blog&amp;utm_medium=social&amp;utm_campaign=inbound-materia-quando-e-como-comecar-a-contar-historias-para-bebes\" target=\"_blank\" rel=\"noreferrer noopener\">Clube <\/a><a href=\"https:\/\/quindim.com.br\/\">Quindim<\/a>, que entrega um kit de livros em casa todo m\u00eas. Ao fazer parte de um clube como o nosso, voc\u00ea n\u00e3o precisa se preocupar em sair para comprar os livros ou procurar por lojas on-line confi\u00e1veis. Al\u00e9m da praticidade, voc\u00ea garante <strong>livros diferentes todo m\u00eas, selecionados de acordo com a idade do beb\u00ea e escolhidos por especialistas <\/strong>em literatura infantil!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com uma <a href=\"https:\/\/quindim.com.br\/?utm_source=blog&amp;utm_medium=social&amp;utm_campaign=inbound-materia-quando-e-como-comecar-a-contar-historias-para-bebes\" target=\"_blank\" rel=\"noreferrer noopener\">assinatura de livro infantil<\/a>, voc\u00ea come\u00e7a a montar uma biblioteca rica, repleta de diversidade e em constante crescimento para seu beb\u00ea. E o Clube Quindim pode ajudar voc\u00ea nessa miss\u00e3o! <a href=\"https:\/\/quindim.com.br\/blog\/como-funciona-o-clube-quindim\/?utm_source=blog&amp;utm_medium=social&amp;utm_campaign=inbound-materia-quando-e-como-comecar-a-contar-historias-para-bebes\" target=\"_blank\" rel=\"noreferrer noopener\">Clique aqui<\/a> para saber como funciona nosso clube de leitura!<\/p>\n\n\n\n<h2 class=\"wp-block-heading subtituloh2\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><strong>Como contar hist\u00f3rias para beb\u00eas?<\/strong><\/mark><\/mark><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o existe certo ou errado quando falamos sobre <a href=\"https:\/\/quindim.com.br\/blog\/como-ler-para-bebes\/?utm_source=blog&amp;utm_medium=social&amp;utm_campaign=inbound-materia-quando-e-como-comecar-a-contar-historias-para-bebes\" target=\"_blank\" rel=\"noreferrer noopener\">contar hist\u00f3rias para beb\u00eas<\/a>. Cada crian\u00e7a \u00e9 \u00fanica e pode ter suas diversas prefer\u00eancias! Mas, para ajudar nesse momento inicial, confira 8 dicas que separamos para a hora da leitura com os beb\u00eas. Vem com a gente!<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh3 has-text-color\" style=\"color:#404040\">1. A posi\u00e7\u00e3o da leitura<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Deitado? Sentado? Olha, n\u00e3o existe posi\u00e7\u00e3o certa ou errada, o que vale \u00e9 descobrir qual a melhor para voc\u00ea e o seu beb\u00ea. Voc\u00ea pode colocar o pequeno sentado no seu colo ou de frente para voc\u00ea. Ou pode at\u00e9 se deitar ao lado dele e segurar o livro sobre voc\u00eas. Teste qual a melhor para os dois ou ent\u00e3o varie de acordo com o dia. Lembre-se: a melhor posi\u00e7\u00e3o para ler com o seu beb\u00ea \u00e9 aquela que voc\u00eas se sentirem mais confort\u00e1veis!<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh3 has-text-color\" style=\"color:#404040\">2. O livro precisa estar vis\u00edvel<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1170\" height=\"730\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes.-Como-ler-para-bebes-1170x730.jpg\" alt=\"Como contar hist\u00f3rias para beb\u00eas. Como ler para beb\u00eas\" class=\"wp-image-25713\" style=\"width:565px;height:352px\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes.-Como-ler-para-bebes.jpg 1170w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes.-Como-ler-para-bebes-768x479.jpg 768w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\"><em>Foto: Canva<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Quando falamos de como contar hist\u00f3rias para beb\u00eas, este \u00e9 um ponto muito importante: <strong>leia com o livro virado para o beb\u00ea<\/strong>. Assim, ele pode acompanhar as ilustra\u00e7\u00f5es e as p\u00e1ginas enquanto voc\u00ea l\u00ea. E, ainda, deixe seu beb\u00ea explorar um pouco as imagens antes de virar a p\u00e1gina, isso pode ser muito interessante para ele!<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh3 has-text-color\" style=\"color:#404040\">3. Atmosfera para ler com o beb\u00ea<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Uma atmosfera tranquila e aconchegante pode potencializar esse momento. Voc\u00ea pode at\u00e9 mesmo montar um <a href=\"https:\/\/quindim.com.br\/blog\/dicas-de-cantinhos-da-leitura-no-quarto-das-criancas\/?utm_source=blog&amp;utm_medium=social&amp;utm_campaign=inbound-materia-quando-e-como-comecar-a-contar-historias-para-bebes\" target=\"_blank\" rel=\"noreferrer noopener\">cantinho ou lugar especial para a leitura<\/a> e aumentar ainda mais o carinho gerado por esse momento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh3 has-text-color\" style=\"color:#404040\">4. Leitura e presen\u00e7a<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1170\" height=\"730\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/07\/Historias-de-animais-para-criancas-1170x730.jpg\" alt=\"Hist\u00f3rias de animais para crian\u00e7as\" class=\"wp-image-26598\" style=\"width:569px;height:355px\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/07\/Historias-de-animais-para-criancas.jpg 1170w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/07\/Historias-de-animais-para-criancas-768x479.jpg 768w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\"><em>Foto: Canva<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Esta \u00e9 uma dica muito importante! Esteja presente durante a leitura com o beb\u00ea e fa\u00e7a desse um momento de qualidade entre voc\u00eas dois. Ou seja, nada de celulares, telas, distra\u00e7\u00f5es ou pressa! Esteja 100% presente para o seu pequeno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Direto do Instagram: <\/strong><a href=\"https:\/\/www.instagram.com\/p\/C5gwYaCp75W\/?img_index=1\" rel=\"nofollow noopener\" target=\"_blank\">8 livros para falar sobre ansiedade de separa\u00e7\u00e3o<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh3 has-text-color\" style=\"color:#404040\">5. As vozes e o ritmo do livro<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Fa\u00e7a <strong>diferentes entona\u00e7\u00f5es de voz<\/strong> de acordo com cada situa\u00e7\u00e3o ou personagem durante a leitura em voz alta. Outra dica importante \u00e9 respeitar os sons e o ritmo do livro. Os sil\u00eancios e as pausas das pontua\u00e7\u00f5es podem ajudar a guiar essa cad\u00eancia, enfatizando efeitos po\u00e9ticos. Se houver onomatopeias no texto, entregue-se tamb\u00e9m \u00e0 brincadeira de reproduzir os diferentes sons. Voc\u00eas ir\u00e3o se divertir!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/quindim.com.br\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"770\" height=\"200\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_LivrosTransformadores.jpg\" alt=\"\" class=\"wp-image-64971\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_LivrosTransformadores.jpg 770w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_LivrosTransformadores-768x199.jpg 768w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_LivrosTransformadores-150x39.jpg 150w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading subtituloh3 has-text-color\" style=\"color:#404040\">6. Pausas para coment\u00e1rios e explica\u00e7\u00f5es<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1170\" height=\"730\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes.-Dicas-para-ler-para-bebes-1170x730.jpg\" alt=\"Como contar hist\u00f3rias para beb\u00eas. Dicas para ler para beb\u00eas\" class=\"wp-image-25714\" style=\"width:571px;height:356px\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes.-Dicas-para-ler-para-bebes.jpg 1170w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes.-Dicas-para-ler-para-bebes-768x479.jpg 768w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\"><em>Foto: Canva<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Muitos pais se perguntam: posso parar a leitura para comentar as ilustra\u00e7\u00f5es, o texto ou explicar uma palavra dif\u00edcil? Sim, com certeza! A leitura \u00e9 um momento de troca, ent\u00e3o n\u00e3o h\u00e1 problema nenhum em fazer pausas explicativas, s\u00f3 tome cuidado para a <strong>leitura n\u00e3o ficar muito did\u00e1tica<\/strong>. Os pequenos podem entender o significado das palavras conforme a encontram em diferentes situa\u00e7\u00f5es. <strong>Ent\u00e3o, n\u00e3o \u00e9 necess\u00e1rio explicar tudo<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh3 has-text-color\" style=\"color:#404040\">7. As rea\u00e7\u00f5es e o tempo do beb\u00ea<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0s vezes, nos planejamos para ler com o beb\u00ea em um determinado hor\u00e1rio, mas temos que prestar aten\u00e7\u00e3o se ele est\u00e1 disposto para a leitura. Perceba quando ele estiver mais calmo e relaxado: esse \u00e9 o melhor momento para ler com a crian\u00e7a. Note para onde ele olha ou aponta, o que ele tenta falar ou imitar durante a leitura. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deixe seu beb\u00ea explorar o livro e converse com ele sobre a hist\u00f3ria. E tudo bem se voc\u00ea n\u00e3o conseguir ler a hist\u00f3ria inteira de uma vez, seja porque a crian\u00e7a est\u00e1 agitada, com fome ou irritada naquele momento. Voc\u00ea pode parar e retomar depois. O importante \u00e9 n\u00e3o for\u00e7ar, pois a leitura n\u00e3o \u00e9 uma obriga\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh3 has-text-color\" style=\"color:#404040\">8. O momento de cada livro<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1170\" height=\"730\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes-de-0-a-2-anos.-Como-ler-para-bebes-1170x730.jpg\" alt=\"Como contar hist\u00f3rias para beb\u00eas de 0 a 2 anos. Como ler para beb\u00eas\" class=\"wp-image-25716\" style=\"width:573px;height:357px\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes-de-0-a-2-anos.-Como-ler-para-bebes.jpg 1170w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes-de-0-a-2-anos.-Como-ler-para-bebes-768x479.jpg 768w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\"><em>Foto: Canva<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Nesta \u00faltima dica para contar hist\u00f3rias para beb\u00eas, precisamos lembrar que n\u00e3o gostar de um livro tamb\u00e9m \u00e9 um processo importante. Afinal, ningu\u00e9m ama todos os livros, filmes e s\u00e9ries que leu ou viu na vida. N\u00e3o gostar de um livro mostra que o pequeno est\u00e1 desenvolvendo sua autonomia e suas pr\u00f3prias prefer\u00eancias. Al\u00e9m do mais, caso a crian\u00e7a n\u00e3o curta essa leitura nesse momento, voc\u00ea pode guard\u00e1-lo para ler no futuro com ele. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E \u00e9 claro que voc\u00ea pode comprar obras parecidas com as que o seu filho j\u00e1 gosta, mas tenha em mente que \u00e9 preciso tamb\u00e9m testar livros novos e n\u00e3o perder a oportunidade de ampliar o repert\u00f3rio dele. Gosto \u00e9 algo constru\u00eddo, por isso, mantenha a mente aberta. Voc\u00ea pode se surpreender com as obras que o seu filho pode curtir. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/conteudo.quindim.com.br\/assinar-newsletter-banner-blog\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"770\" height=\"200\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_RecebaDicas.jpg\" alt=\"\" class=\"wp-image-64972\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_RecebaDicas.jpg 770w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_RecebaDicas-768x199.jpg 768w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2024\/08\/BannerConteudo_RecebaDicas-150x39.jpg 150w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading subtituloh2\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#f27059\" class=\"has-inline-color\"><strong><strong>Principais d\u00favidas<\/strong><\/strong><\/mark><\/mark> dos pais sobre a leitura com beb\u00cas<\/h2>\n\n\n\n<h3 class=\"wp-block-heading subtituloh3 has-text-color\" style=\"color:#404040\">1. O que fazer quando o beb\u00ea n\u00e3o se interessa pelo livro ou fica muito agitado durante a leitura?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea pode pensar que o beb\u00ea n\u00e3o gosta de ler ou n\u00e3o se interessou por um determinado livro, mas o que pode estar acontecendo \u00e9 seu beb\u00ea n\u00e3o estar dispon\u00edvel para a leitura naquele momento. <strong>Procure um hor\u00e1rio em que ele esteja mais tranquilo<\/strong>. Fa\u00e7a pequenos testes: tente ler ap\u00f3s uma refei\u00e7\u00e3o, no meio da manh\u00e3, depois da soneca ou de um passeio. Cada crian\u00e7a \u00e9 \u00fanica. Aos poucos, voc\u00ea vai perceber os momentos em que a crian\u00e7a se concentra melhor e acolhe a leitura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh3 has-text-color\" style=\"color:#404040\">2. E se o beb\u00ea rasgar o livro?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Essa \u00e9 uma preocupa\u00e7\u00e3o constante dos adultos. Assim como v\u00e1rios brinquedos tamb\u00e9m s\u00e3o quebrados no dia a dia, os livros n\u00e3o ficar\u00e3o intactos. \u00c9 natural que alguns livros sejam amassados ou rasgados, j\u00e1 que seu beb\u00ea ainda n\u00e3o controla sua for\u00e7a. Mesmo assim, os livros precisam estar ao alcance dos pequenos, pois \u00e9 assim que eles ir\u00e3o aprender a manuse\u00e1-los. Deixar o beb\u00ea em contato com o papel \u00e9 um aprendizado, j\u00e1 que, dessa maneira, ele desenvolver\u00e1 a <a href=\"https:\/\/quindim.com.br\/blog\/coordenacao-motora-do-bebe\/?utm_source=blog&amp;utm_medium=social&amp;utm_campaign=inbound-materia-quando-e-como-comecar-a-contar-historias-para-bebes\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>motricidade fina<\/strong><\/a> necess\u00e1ria para o virar das p\u00e1ginas, por exemplo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Claro que no come\u00e7o voc\u00ea pode mostrar o livro para seu beb\u00ea com certa dist\u00e2ncia para ele n\u00e3o estragar, mas \u00e9 importante que ele explore a obra. Quando o beb\u00ea entra em contato e interage com o livro \u00e9 o momento em que ele est\u00e1 descobrindo esse objeto e criando conex\u00f5es com ele. E <strong>isso \u00e9 fundamental na forma\u00e7\u00e3o de um leitor<\/strong>!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"1170\" height=\"730\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes.-Como-ler-para-bebes-de-0-a-2-anos-1170x730.jpg\" alt=\"Como contar hist\u00f3rias para beb\u00eas. Como ler para beb\u00eas de 0 a 2 anos\" class=\"wp-image-25717\" style=\"width:567px;height:354px\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes.-Como-ler-para-bebes-de-0-a-2-anos.jpg 1170w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/06\/Como-contar-historias-para-bebes.-Como-ler-para-bebes-de-0-a-2-anos-768x479.jpg 768w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><figcaption class=\"wp-element-caption\"><em>Foto: Canva<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Se em algum momento ele morder, babar, rasgar ou riscar o livro, n\u00e3o fique triste. Isso mostra que ele est\u00e1 desenvolvendo uma rela\u00e7\u00e3o com o objeto. Quando isso acontecer aproveite a oportunidade e mostre ao pequeno como ele pode manusear a obra sem que isso aconte\u00e7a numa pr\u00f3xima vez! Mesmo que alguns estragos sejam inevit\u00e1veis, voc\u00eas ainda podem desfrutar da hist\u00f3ria e aproveitar a leitura. <strong>Muitas vezes s\u00e3o essas obras cheias de remendos que v\u00e3o ficar na mem\u00f3ria de voc\u00eas<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading subtituloh3 has-text-color\" style=\"color:#404040\">3. O beb\u00ea entende o que voc\u00ea l\u00ea com ele?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 comum ficar receoso ao contar uma hist\u00f3ria mais longa ou com palavras mais \u201cdif\u00edceis\u201d para um beb\u00ea, porque, afinal, eles est\u00e3o desenvolvendo o vocabul\u00e1rio aos poucos. O pequeno pode n\u00e3o entender exatamente o que voc\u00ea diz ou compreender todas as camadas de uma hist\u00f3ria, mas est\u00e1 prestando aten\u00e7\u00e3o no ritmo da sua voz, no som das palavras e no tom do texto. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com o tempo, o pequeno vai associar o som daquela palavra com determinada situa\u00e7\u00e3o e assim vai entender seu significado. Por isso, apresentar diferentes palavras \u00e9 essencial para os beb\u00eas se familiarizarem com elas e ampliarem seu vocabul\u00e1rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para criar o h\u00e1bito de leitura com seu beb\u00ea, conte com o <a href=\"https:\/\/quindim.com.br\/?utm_source=blog&amp;utm_medium=social&amp;utm_campaign=inbound-materia-quando-e-como-comecar-a-contar-historias-para-bebes\" target=\"_blank\" rel=\"noreferrer noopener\">Clube Quindim<\/a> e receba os melhores livros infantis para seu pequeno.<\/p>\n\n\n\n<h2 class=\"wp-block-heading subtituloh2\">Estante Quindim<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Conhe\u00e7a 3 dicas de livros infantis para ler com seu beb\u00ea. Esses t\u00edtulos j\u00e1 foram enviados pelo Clube Quindim aos seus assinantes.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"437\" height=\"310\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/05\/DezPatinhosCapa_Transparente-e1698168213528.png\" alt=\"Dez patinhos (autora Gra\u00e7a Lima, editora Companhia das Letrinhas)\" class=\"wp-image-54798\" style=\"aspect-ratio:1;object-fit:contain\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/05\/DezPatinhosCapa_Transparente-e1698168213528.png 437w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/05\/DezPatinhosCapa_Transparente-e1698168213528-150x106.png 150w\" sizes=\"(max-width: 437px) 100vw, 437px\" \/><figcaption class=\"wp-element-caption\"><em><a href=\"https:\/\/quindim.com.br\/selecoes\/livro\/dez-patinhos\/graca-lima\/9788574064222\" target=\"_blank\" rel=\"noreferrer noopener\">Dez patinhos<\/a><\/em>, de Gra\u00e7a Lima<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"283\" height=\"328\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/03\/Livro-Dia-de-Sol-de-Renato-Moriconi.jpg\" alt=\"Livro Dia de Sol de Renato Moriconi\" class=\"wp-image-45684\" style=\"aspect-ratio:1;object-fit:contain\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/03\/Livro-Dia-de-Sol-de-Renato-Moriconi.jpg 283w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2022\/03\/Livro-Dia-de-Sol-de-Renato-Moriconi-150x174.jpg 150w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/><figcaption class=\"wp-element-caption\"><em><a href=\"https:\/\/quindim.com.br\/selecoes\/livro\/dia-de-sol\/renato-moriconi\/9786589830108\" target=\"_blank\" rel=\"noreferrer noopener\">Dia de Sol<\/a><\/em>, de Renato Moriconi<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"451\" height=\"338\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/04\/AchouCapaTransparente-edited-1.png\" alt=\"Achou? (autora Aline Abreu, editora Companhia das Letrinhas)\" class=\"wp-image-49501\" style=\"aspect-ratio:1;object-fit:contain\" title=\"\" srcset=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/04\/AchouCapaTransparente-edited-1.png 451w, https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2023\/04\/AchouCapaTransparente-edited-1-150x112.png 150w\" sizes=\"(max-width: 451px) 100vw, 451px\" \/><figcaption class=\"wp-element-caption\"><em><a href=\"https:\/\/quindim.com.br\/selecoes\/livro\/achou%3F\/aline-abreu\/9788574069326\" target=\"_blank\" rel=\"noreferrer noopener\">Achou?<\/a><\/em>, de Aline Abreu<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Tem d\u00favidas de como contar hist\u00f3rias para beb\u00eas? Confira as dicas que o Quindim separou para voc\u00ea come\u00e7ar a ler hoje com seu pequeno.<\/p>\n","protected":false},"author":23,"featured_media":61027,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[497,746,498,514,4,505,499,507,508],"tags":[],"class_list":["post-25680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-livros-infantis","category-desenvolvimento-infantil","category-dicas-para-gostar-de-ler","category-educacao-familia","category-educacao","category-familia","category-literatura-infantil","category-maternidade","category-paternidade"],"acf":{"posts_relacionados":[163,10988,35814]},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/25680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/comments?post=25680"}],"version-history":[{"count":0,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/25680\/revisions"}],"acf:post":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/35814"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/10988"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media\/61027"}],"wp:attachment":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media?parent=25680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/categories?post=25680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/tags?post=25680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}