{"id":1677,"date":"2018-11-01T17:00:03","date_gmt":"2018-11-01T20:00:03","guid":{"rendered":"https:\/\/blog.clubequindim.com.br\/?p=1677"},"modified":"2021-12-28T16:00:47","modified_gmt":"2021-12-28T19:00:47","slug":"8-maneiras-enriquecer-cultura-filho","status":"publish","type":"post","link":"https:\/\/quindim.com.br\/blog\/8-maneiras-enriquecer-cultura-filho\/","title":{"rendered":"8 maneiras de enriquecer a cultura do seu filho"},"content":{"rendered":"\n<h2 class=\"subtituloh2 wp-block-heading\"><span style=\"color:#f27059\" class=\"has-inline-color\"><span style=\"color:#f27059\" class=\"has-inline-color\">Como enriquecer a cultura do seu filho?<\/span><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A cultura est\u00e1 em tudo. Nas festas populares, no filme que nos diverte, na televis\u00e3o e nas hist\u00f3rias que ouvimos ao longo da vida. E mais: a cultura permite construir a sua identidade, entender a vida do seu povo e olhar com generosidade para a dos outros. Assim, agrega toler\u00e2ncia, empatia e paz. N\u00e3o \u00e9 \u00e0 toa que enriquecer a cultura das crian\u00e7as \u00e9 t\u00e3o fundamental. Mas como estimular essa a\u00e7\u00e3o no dia a dia? A equipe do Clube Quindim separou algumas dicas:<\/p>\n\n\n\n<h3 class=\"subtituloh3 has-text-color wp-block-heading\" style=\"color:#404040\">1. Apresente arte<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">As galerias e os museus s\u00e3o espa\u00e7os perfeitos para uma visita divertida com as crian\u00e7as. Ali, elas percebem que uma obra de arte \u00e9 uma pe\u00e7a a ser valorizada, por isso ganha um territ\u00f3rio todo especial para ela. E que muitas vezes a arte n\u00e3o est\u00e1 diretamente associada a um apuro t\u00e9cnico, mas a um inc\u00f4modo, uma performance, uma sensa\u00e7\u00e3o, uma cr\u00edtica etc. Al\u00e9m disso, as obras podem contar hist\u00f3rias de diferentes civiliza\u00e7\u00f5es, de pensadores e artistas de lugares distintos daquele em que voc\u00eas vivem, enriquecendo n\u00e3o s\u00f3 a cultura mas tamb\u00e9m o aprendizado escolar. Outra compet\u00eancia trabalhada nesse tipo de programa \u00e9 a sensibilidade para apreciar um trabalho, e se permitir envolver por ele, refletindo e articulando al\u00e9m do &#8220;gosto&#8221; ou &#8220;n\u00e3o gosto&#8221;. Por isso, no passeio, estimule o di\u00e1logo, perguntando de que obra a crian\u00e7a gostou mais e o que a tocou nesse trabalho.<\/p>\n\n\n\n<h3 class=\"subtituloh3 has-text-color wp-block-heading\" style=\"color:#404040\">2. Desperte criatividade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mostrar que a crian\u00e7a tamb\u00e9m pode ser um sujeito criador, colocando-a em di\u00e1logo com outras obras de arte, \u00e9 outra forma de enriquecer sua cultura. Com tintas, l\u00e1pis e recortes, ela pode exercitar a criatividade e dar vaz\u00e3o \u00e0s suas emo\u00e7\u00f5es e aos seus pensamentos. Depois, voc\u00eas podem conversar sobre o que ela fez, e voc\u00ea pode trazer refer\u00eancia de artistas que tenham alguma afinidade com a cria\u00e7\u00e3o dela. Isso ir\u00e1 instigar a curiosidade para ela saber mais sobre eles e assim ampliar o repert\u00f3rio dela.<\/p>\n\n\n\n<h3 class=\"subtituloh3 has-text-color wp-block-heading\" style=\"color:#404040\">3. Mostre m\u00fasica<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A m\u00fasica desenvolve o senso est\u00e9tico, as no\u00e7\u00f5es de ritmo e o reconhecimento da escuta. Tamb\u00e9m nos fala sobre a cultura de outros povos, desperta a sensibilidade e ensina a organizar o pensamento. Introduzir a crian\u00e7a ao aprendizado de um instrumento musical pode ser muito rico nesse processo. Al\u00e9m disso, vale lev\u00e1-la a espet\u00e1culos musicais e apresentar ritmos diversos, como m\u00fasica cl\u00e1ssica, samba e MPB. Para saber mais sobre os benef\u00edcios da musicaliza\u00e7\u00e3o, acesse <a href=\"https:\/\/blog.clubequindim.com.br\/musica-na-infancia-beneficios-e-dicas-para-estimular\/\">este<\/a> artigo do nosso blog.<\/p>\n\n\n\n<h3 class=\"subtituloh3 has-text-color wp-block-heading\" style=\"color:#404040\">4. Encante com o cinema<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O cinema \u00e9 uma arte que agrega sons e imagens, despertando os sentidos dos pequenos e apresentando temas importantes. Por meio dos filmes, eles podem pensar sobre suas experi\u00eancias e vivenciar situa\u00e7\u00f5es que dificilmente acessariam de outra forma. Ensina sobre linguagem e estimula a criatividade. Para enriquecer esse ensinamento, mostre filmes infantis de qualidade. A equipe do Clube Quindim separou <a href=\"https:\/\/blog.clubequindim.com.br\/filme-nas-ferias-7-adaptacoes-da-literatura-infantil\/\">sete indica\u00e7\u00f5es dessas produ\u00e7\u00f5es<\/a>, baseadas em literatura infantil.<\/p>\n\n\n\n<h3 class=\"subtituloh3 has-text-color wp-block-heading\" style=\"color:#404040\">5. Viva a cidade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea j\u00e1 parou para pensar nas hist\u00f3rias que a cidade conta? Com um passeio no parque, voc\u00ea pode falar com seu filho sobre a preserva\u00e7\u00e3o da natureza, os cuidados com o lixo e a hist\u00f3ria por tr\u00e1s do local. Conviver com pessoas diferentes nos espa\u00e7os p\u00fablicos tamb\u00e9m ensina sobre a import\u00e2ncia da inclus\u00e3o, da toler\u00e2ncia e de compartilhar a vida. Al\u00e9m disso, \u00e9 uma forma de preparar a crian\u00e7a para ter mais autonomia, ensinando a transitar sobre diferentes espa\u00e7os al\u00e9m daqueles familiares e dentro da zona de conforto dela.<\/p>\n\n\n\n<h3 class=\"subtituloh3 has-text-color wp-block-heading\" style=\"color:#404040\">6. Busque especialistas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Grandes pesquisadores da cultura deixaram trabalhos capazes de inspirar e enriquecer a forma\u00e7\u00e3o cultural das crian\u00e7as. Lu\u00eds da C\u00e2mara Cascudo \u00e9 um bom exemplo. Com seu trabalho documentando o folclore, contribuiu para a valoriza\u00e7\u00e3o desse patrim\u00f4nio nacional. Apresente essas hist\u00f3rias ao seu filho e destaque a import\u00e2ncia desse trabalho. Aqui, separamos algumas<a href=\"https:\/\/blog.clubequindim.com.br\/5-personagens-do-folclore-que-as-criancas-vao-amar-conhecer\/\"> figuras fundamentais do folclore<\/a>, e, aqui,<a href=\"https:\/\/blog.clubequindim.com.br\/folclore-livros-que-apresentam-a-cultura-e-a-identidade-para-as-criancas\/\"> livros que valem a pena ser consultados<\/a>.<\/p>\n\n\n\n<h3 class=\"subtituloh3 has-text-color wp-block-heading\" style=\"color:#404040\">7. Converse sobre diversidade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como vivem os povos de pa\u00edses africanos? E das tribos ind\u00edgenas brasileiras? Tudo isso \u00e9 cultura. Esse conhecimento amplia nossa vis\u00e3o de mundo e nosso repert\u00f3rio cultural. Ensina, ainda, a desconstruir o olhar julgador que carregamos, aprendendo a reconhecer e respeitar outras manifesta\u00e7\u00f5es art\u00edsticas e formas de viver. Livros e filmes sobre outras culturas podem ajudar muito a enriquecer essa compreens\u00e3o.<\/p>\n\n\n\n<h3 class=\"subtituloh3 has-text-color wp-block-heading\" style=\"color:#404040\">8. Leia para o seu filho<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os benef\u00edcios da leitura s\u00e3o in\u00fameros, fundamentais para um amplo desenvolvimento da inf\u00e2ncia. Ler com a crian\u00e7a n\u00e3o s\u00f3 trabalha esses benef\u00edcios como fortalece o v\u00ednculo familiar e proporciona aprendizados inesquec\u00edveis para todos. Ler permite vivenciar outras experi\u00eancias e assim ampliar nossa cultura e vis\u00e3o de mundo, nos tornando mais emp\u00e1ticos e tolerantes. Escolher os livros de qualidade, contudo, nem sempre \u00e9 tarefa f\u00e1cil no dia a dia, com tantos apelos comerciais em livrarias que oferecem obras de personagens licenciados que mais refor\u00e7am estere\u00f3tipos do que desenvolvem o pensamento cr\u00edtico e aut\u00f4nomo. Por isso, acionar um clube de assinaturas como o Clube Quindim pode ajudar muito. Confira <a href=\"https:\/\/blog.clubequindim.com.br\/motivos-assinar-clube-de-leitura-quindim\/\">aqui<\/a> dez motivos para fazer isso.<\/p>\n\n\n\n<div class=\"wp-block-columns bloco-cta has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#fdb813\">\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/quindim.com.br\/\"><img decoding=\"async\" width=\"434\" height=\"195\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2020\/07\/call01.png\" alt=\"Assine o Clube Quindim\" class=\"wp-image-9392\" title=\"\"><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column bloco-cta-direita is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center titulo-cta wp-block-paragraph\"><span style=\"color:#f27059\" class=\"has-inline-color\">APROVEITE ESTE MOMENTO PARA INCENTIVAR A LEITURA!<\/span><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100 botao-cta is-style-fill\"><a class=\"wp-block-button__link\" href=\"https:\/\/quindim.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color:#e3e2e2\" class=\"has-inline-color\">ASSINE O CLUBE QUINDIM E RECEBA OS MELHORES LIVROS INFANTIS!<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Como enriquecer a cultura do seu filho? A cultura est\u00e1 em tudo. Nas festas populares, no filme que nos diverte, na televis\u00e3o e nas hist\u00f3rias que ouvimos ao longo da vida. E mais: a cultura permite construir a sua identidade, entender a vida do seu povo e olhar com generosidade para a dos outros. Assim, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[511,514],"tags":[],"class_list":["post-1677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diversao","category-educacao-familia"],"acf":{"posts_relacionados":[24651,10864,10661]},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/1677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1677"}],"version-history":[{"count":0,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/1677\/revisions"}],"acf:post":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/10661"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/10864"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/24651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media\/1692"}],"wp:attachment":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}