{"id":1157,"date":"2018-07-26T00:01:42","date_gmt":"2018-07-26T03:01:42","guid":{"rendered":"https:\/\/blog.clubequindim.com.br\/?p=1157"},"modified":"2021-12-28T17:03:54","modified_gmt":"2021-12-28T20:03:54","slug":"5-avos-adoraveis-da-literatura-infantil-brasileira","status":"publish","type":"post","link":"https:\/\/quindim.com.br\/blog\/5-avos-adoraveis-da-literatura-infantil-brasileira\/","title":{"rendered":"5 av\u00f3s ador\u00e1veis da literatura infantil brasileira"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Colo de av\u00f4 e av\u00f3 \u00e9 de uma del\u00edcia sem fim, e tem gostinho de guloseimas, brincadeiras e amor incondicional. Essa rela\u00e7\u00e3o dos av\u00f3s e netos \u00e9 cercada de leveza e alegria, ensina muito sobre paci\u00eancia e a import\u00e2ncia de respeitar o saber de cada gera\u00e7\u00e3o, al\u00e9m de renovar as energias dos mais velhos. Para celebrar o Dia dos Av\u00f3s, comemorado em 26 de julho, reunimos alguns livros que trazem esses deliciosos personagens como protagonistas, olha s\u00f3:<\/p>\n\n\n\n<div class=\"wp-block-columns lista-de-livros-container is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-image lista-de-livros-texto-imagem\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"360\" height=\"420\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/10\/a-alegre-vovo-guida.jpg\" alt=\"Av\u00f3s na literatura infantil. A alegre vov\u00f3 Guida, que \u00e9 muito distra\u00edda, da autora Tatiana Belinky\" class=\"wp-image-33802\" title=\"\"><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"lista-de-livros wp-block-heading\">A ALEGRE VOV\u00d3 GUIDA QUE \u00c9 UM BOCADO DISTRA\u00cdDA (Tatiana Belinky)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A atrapalhada vov\u00f3 desta hist\u00f3ria leva um queijo a tiracolo enquanto p\u00f5e a bolsa na geladeira, al\u00e9m de dar leite ao gato em um sapato e de cal\u00e7ar uma peruca. Esse jeitinho distra\u00eddo e ador\u00e1vel, comum a muitos idosos, \u00e9 costurado em versos que v\u00e3o divertir as crian\u00e7as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A criadora da personagem \u00e9 Tatiana Belinky, autora que nasceu na R\u00fassia e cresceu no Brasil. Ela publicou mais de 200 livros, muitos deles para o p\u00fablico infantil, e se orgulhava de ter muitos netos e bisnetos. Assista \u00e0 narra\u00e7\u00e3o da hist\u00f3ria no canal Faf\u00e1 conta hist\u00f3rias:<\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"A ALEGRE VOV\u00d3 GUIDA, QUE \u00c9 UM BOCADO DISTRA\u00cdDA, DE TATIANA BELINKY, por Faf\u00e1 conta LEGENDA EM PORT.\" width=\"810\" height=\"456\" src=\"https:\/\/www.youtube.com\/embed\/ywZDK2xbyEs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div class=\"wp-block-columns lista-de-livros-container is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-image lista-de-livros-texto-imagem\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"360\" height=\"494\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/10\/a-casa-do-meu-avo.jpg\" alt=\"Av\u00f3s. A casa do meu av\u00f4\" class=\"wp-image-33804\" title=\"\"><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"lista-de-livros wp-block-heading\">A CASA DO MEU AV\u00d4 (Ricardo Azevedo)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Casa de v\u00f4 \u00e9 aquela bagun\u00e7a gostosa, onde vivemos aventuras e conhecemos as coisas mais loucas! A casa desta hist\u00f3ria \u00e9 fascinante porque \u00e9 cheia de personagens curiosos, como uma cozinheira que parece fazer feiti\u00e7o, um tio meio biruta, um cachorro para l\u00e1 de bravo e um jardineiro m\u00e1gico. Pelas p\u00e1ginas deste livro, que re\u00fane uma s\u00e9rie de poemas, conhecemos os mist\u00e9rios e os amores que rondam a casa do vov\u00f4, sempre protetor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ricardo Azevedo, autor do livro, escreveu diversas obras para crian\u00e7as e jovens, publicadas no Brasil e no exterior. Tamb\u00e9m ganhou pr\u00eamios como o Jabuti e o APCA, al\u00e9m de ser um dos curadores do Clube Quindim, selecionando os livros que chegam \u00e0s casas das crian\u00e7as todos os meses. Para saber mais, acesse o&nbsp;<a href=\"http:\/\/www.ricardoazevedo.com.br\/\" rel=\"nofollow noopener\" target=\"_blank\">site<\/a>&nbsp;do autor.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns lista-de-livros-container is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-image lista-de-livros-texto-imagem\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"360\" height=\"522\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/10\/reinacoes-de-narizinho-1.jpg\" alt=\"Av\u00f3s na literatura infantil. Reina\u00e7\u00f5es de Narizinho, do autor Monteiro Lobato\" class=\"wp-image-33805\" title=\"\"><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"lista-de-livros wp-block-heading\">REINA\u00c7\u00d5ES DE NARIZINHO (Monteiro Lobato)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Logo nas primeiras linhas deste cl\u00e1ssico da literatura brasileira, conhecemos a velhinha de mais de 60 anos, de \u201ccestinha de costura ao colo e \u00f3culos de ouro na ponta do nariz\u201d. Dona Benta \u00e9 descrita pelo autor como \u201ca mais feliz das vov\u00f3s\u201d! Afinal, vive com sua netinha Narizinho, sua fiel escudeira Tia Nast\u00e1cia e a boneca Em\u00edlia. Ainda recebe a visita do neto Pedrinho e de outros personagens fant\u00e1sticos, como o Visconde de Sabugosa e o porco Rabic\u00f3 \u2013 sem mencionar o rinoceronte Quindim, nossa grande inspira\u00e7\u00e3o!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cheia de amor e paci\u00eancia, e sempre disposta a dividir sua enorme sabedoria com todos \u00e0 sua volta, Dona Benta \u00e9 uma vov\u00f3 inesquec\u00edvel, presente em toda a saga do S\u00edtio do Picapau Amarelo. N\u00f3s, aqui do Clube de Leitura Quindim, falamos mais da obra de Lobato e da import\u00e2ncia de conhec\u00ea-la&nbsp;<a href=\"https:\/\/blog.clubequindim.com.br\/por-que-ler-monteiro-lobato-doze-razoes\/\">aqui<\/a>.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns lista-de-livros-container is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-image lista-de-livros-texto-imagem\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"360\" height=\"532\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/10\/vovo-delicia.jpg\" alt=\"Av\u00f3s na literatura infantil. Vov\u00f3 del\u00edcia do Ziraldo\" class=\"wp-image-33807\" title=\"\"><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"lista-de-livros wp-block-heading\">VOV\u00d3 DEL\u00cdCIA (Ziraldo)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Um dos autores mais celebrados da literatura infantil brasileira, e curador do Clube Quindim, criou esta amada personagem. A av\u00f3 diferente daquela que ficava sentada em cadeira de balan\u00e7o, fazendo croch\u00ea, que encanta seus netinhos com seu jeito brincalh\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vov\u00f3 Del\u00edcia \u00e9 moderna, vai \u00e0 academia, dan\u00e7a, curte uma praia, tem v\u00e1rios amigos e at\u00e9 sofre por amor. Al\u00e9m de tudo isso, tem sempre um colinho gostoso para a neta, sua companheira de aventuras. \u00c9 a av\u00f3 perfeita para os tempos atuais!<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns lista-de-livros-container is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-image lista-de-livros-texto-imagem\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"360\" height=\"428\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2021\/10\/a-vovo-virou-bebe.jpg\" alt=\"Av\u00f3s na literatura infantil. A vov\u00f3 virou beb\u00ea\" class=\"wp-image-33808\" title=\"\"><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"lista-de-livros wp-block-heading\">A VOV\u00d3 VIROU BEB\u00ca (Renata Paiva)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para al\u00e9m dos momentos de leveza e divers\u00e3o, o conv\u00edvio com os av\u00f3s tamb\u00e9m ensina \u00e0s crian\u00e7as sobre o processo natural do envelhecimento e sobre a finitude da vida. \u00c9 isso o que a vov\u00f3 Dorinha, personagem deste livro t\u00e3o sens\u00edvel e delicado, ensina \u00e0 Sofia, sua neta de 7 anos. A menina adora passar muito tempo com sua vov\u00f3, at\u00e9 que ela come\u00e7a a fazer algumas coisas estranhas, como abotoar a blusa errado e esquecer o que estava fazendo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com o apoio de sua m\u00e3e, Sofia entende que a av\u00f3 tem Alzheimer e que, para ajud\u00e1-la, \u00e9 preciso ter paci\u00eancia e carinho.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns bloco-cta has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#fdb813\">\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/quindim.com.br\/\"><img decoding=\"async\" width=\"434\" height=\"195\" src=\"https:\/\/quindim.com.br\/blog\/wp-content\/uploads\/2020\/07\/call01.png\" alt=\"Assine o Clube Quindim\" class=\"wp-image-9392\" title=\"\"><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column bloco-cta-direita is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center titulo-cta wp-block-paragraph\"><span style=\"color:#f27059\" class=\"has-inline-color\">APROVEITE ESTE MOMENTO PARA INCENTIVAR A LEITURA!<\/span><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100 botao-cta is-style-fill\"><a class=\"wp-block-button__link\" href=\"https:\/\/quindim.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color:#e3e2e2\" class=\"has-inline-color\">ASSINE O CLUBE QUINDIM E RECEBA OS MELHORES LIVROS INFANTIS!<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Colo de av\u00f4 e av\u00f3 \u00e9 de uma del\u00edcia sem fim, e tem gostinho de guloseimas, brincadeiras e amor incondicional. Essa rela\u00e7\u00e3o dos av\u00f3s e netos \u00e9 cercada de leveza e alegria, ensina muito sobre paci\u00eancia e a import\u00e2ncia de respeitar o saber de cada gera\u00e7\u00e3o, al\u00e9m de renovar as energias dos mais velhos. Para [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":24040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[499,513],"tags":[],"class_list":["post-1157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-literatura-infantil","category-datas-especiais"],"acf":{"posts_relacionados":[26828,28885,3166]},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/1157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1157"}],"version-history":[{"count":0,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/1157\/revisions"}],"acf:post":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/3166"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/28885"},{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/posts\/26828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media\/24040"}],"wp:attachment":[{"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quindim.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}